{"id":5549,"date":"2025-12-09T12:17:17","date_gmt":"2025-12-09T11:17:17","guid":{"rendered":"https:\/\/parcoarcheologico.cortonamaec.org\/senza-categoria\/singing-the-middle-ages\/"},"modified":"2026-03-10T12:30:06","modified_gmt":"2026-03-10T11:30:06","slug":"singing-the-middle-ages","status":"publish","type":"post","link":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/","title":{"rendered":"Singing the Middle Ages"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-left:0px;--awb-padding-right-small:30px;--awb-padding-left-small:30px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:75%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.56%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.56%;--awb-width-medium:75%;--awb-order-medium:0;--awb-spacing-right-medium:2.56%;--awb-spacing-left-medium:2.56%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-bottom:25px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:38;line-height:var(--awb-typography1-line-height);\">The Lauda in Cortona Between Devotion and Civic Identity<\/h2><\/div><div class=\"fusion-text fusion-text-1\"><p data-start=\"396\" data-end=\"796\">The exhibition brings together for the first time the four Cortona laudari, a unique treasure in Italy\u2019s cultural history and a key testimony to the birth of poetry and music in the vernacular. At its centre is the renowned Laudario di Cortona (ms. 91), the oldest known collection of songs in the Italian language, presented alongside the other manuscripts preserved in Cortona, Arezzo and Milan.<\/p>\n<p data-start=\"798\" data-end=\"1098\">Through manuscripts, medieval documents, works of art and multimedia installations, the exhibition traces the spread of devotional song between the thirteenth and fourteenth centuries and highlights the role of confraternities, churches and the urban community in shaping the spiritual and civic identity of medieval Cortona.<\/p>\n<p data-start=\"1100\" data-end=\"1378\">The exhibition also explores the city\u2019s historical context\u2014from the conflicts between Guelphs and Ghibellines to the rise of the Casali Signoria\u2014and presents significant artistic evidence, including the thirteenth-century painted Cross and the panel depicting the Stories of Santa Margherita.<\/p>\n<p data-start=\"1380\" data-end=\"1706\">A large section is dedicated to the reconstruction of the Laudesi Chapel of San Francesco and to the urban sites connected with the laudistic tradition. The project is completed by musical listening stations, digital access to the manuscripts and a programme of events, concerts and an international conference devoted to the origins of the lauda.<\/p>\n<\/div><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\" style=\"--more-btn-alignment:center;margin-top:20px;margin-bottom:30px;\" data-limit=\"9\" data-page=\"1\"><div style=\"margin:-5px;--awb-aspect-ratio:3 \/ 2;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-9 fusion-gallery-layout-grid fusion-gallery-1 has-aspect-ratio\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/10.Calice-Casali_-Museo-Diocesano-di-Cortona-scaled.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/10.Calice-Casali_-Museo-Diocesano-di-Cortona-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"10.Calice Casali_ Museo Diocesano di Cortona\" aria-label=\"10.Calice Casali_ Museo Diocesano di Cortona\" class=\"img-responsive wp-image-5517 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/04.-Cod.-Triv.-535-63.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/04.-Cod.-Triv.-535-63-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"04. Cod. Triv. 535-63\" aria-label=\"04. Cod. Triv. 535-63\" class=\"img-responsive wp-image-5525 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/02.-Antifonario_ms-4-0813_Biblioteca-Cortona.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/02.-Antifonario_ms-4-0813_Biblioteca-Cortona-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"02. Antifonario_ms 4-0813_Biblioteca Cortona\" aria-label=\"02. Antifonario_ms 4-0813_Biblioteca Cortona\" class=\"img-responsive wp-image-5529 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/06.-Biblioteca-di-Arezzo_MS_180_Laudario-Cortonese.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/06.-Biblioteca-di-Arezzo_MS_180_Laudario-Cortonese-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"06. Biblioteca di Arezzo_MS_180_Laudario Cortonese\" aria-label=\"06. Biblioteca di Arezzo_MS_180_Laudario Cortonese\" class=\"img-responsive wp-image-5521 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/12.-Veduta-della-mostra-con-Laudari-e-tavole.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/12.-Veduta-della-mostra-con-Laudari-e-tavole-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"12. Veduta della mostra con Laudari e tavole\" aria-label=\"12. Veduta della mostra con Laudari e tavole\" class=\"img-responsive wp-image-5513 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/05.-Manoscritto-del-Monastero-di-Santa-Chiara_-Legenda-del-beato-Guido-0807.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/05.-Manoscritto-del-Monastero-di-Santa-Chiara_-Legenda-del-beato-Guido-0807-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"05. Manoscritto del Monastero di Santa Chiara_ Legenda del beato Guido-0807\" aria-label=\"05. Manoscritto del Monastero di Santa Chiara_ Legenda del beato Guido-0807\" class=\"img-responsive wp-image-5523 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/11.-Veduta-della-mostra-con-Laudari-e-tavola-Santa-Margherita.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/11.-Veduta-della-mostra-con-Laudari-e-tavola-Santa-Margherita-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"11. Veduta della mostra con Laudari e tavola Santa Margherita\" aria-label=\"11. Veduta della mostra con Laudari e tavola Santa Margherita\" class=\"img-responsive wp-image-5515 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/03.-Biblioteca-di-Cortona_Miscellaneo1.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/03.-Biblioteca-di-Cortona_Miscellaneo1-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"03. Biblioteca di Cortona_Miscellaneo1\" aria-label=\"03. Biblioteca di Cortona_Miscellaneo1\" class=\"img-responsive wp-image-5527 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/08.-MAEC_Sigillo-del-Comune-di-Cortona-0837-1.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/08.-MAEC_Sigillo-del-Comune-di-Cortona-0837-1-460x295.webp\" width=\"460\" height=\"295\" alt=\"MAEC Cortona mostra &quot;Cantare il Medioevo. La lauda a Cortona tra devozione e identit\u00e0 civica.&quot; 2025\" title=\"08. MAEC_Sigillo del Comune di Cortona-0837 (1)\" aria-label=\"08. MAEC_Sigillo del Comune di Cortona-0837 (1)\" class=\"img-responsive wp-image-5519 fusion-gallery-image-size-fixed\"  \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 awb-sticky awb-sticky-medium awb-sticky-large fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:2;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;--awb-sticky-offset:145px;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:20;--minFontSize:20;line-height:var(--awb-typography1-line-height);\"><strong>Information<\/strong><\/h2><\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-line-height:1.2;\"><p>28 June 2025 &#8211; 05 October 2025<\/p>\n<p>MAEC<br \/>\nPiazza Signorelli, 9<br \/>\nCortona (AR)<\/p>\n<\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;--fontSize:20;--minFontSize:20;line-height:var(--awb-typography1-line-height);\"><strong>Insights and Downloads<\/strong><\/h2><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-span-yes \" style=\"--awb-margin-bottom:5px;--awb-padding-top:10px;--awb-padding-right:20px;--awb-padding-bottom:10px;--awb-padding-left:20px;--button_accent_color:var(--awb-color8);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_gradient_top_color:var(--awb-color4);--button_gradient_bottom_color:var(--awb-color4);--button_gradient_top_color_hover:hsla(var(--awb-color4-h),calc(var(--awb-color4-s) - 5%),calc(var(--awb-color4-l) - 10%),var(--awb-color4-a));--button_gradient_bottom_color_hover:hsla(var(--awb-color4-h),calc(var(--awb-color4-s) - 5%),calc(var(--awb-color4-l) - 10%),var(--awb-color4-a));--button_text_transform:capitalize;--button_font_size:12px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/parcoarcheologico.cortonamaec.org\/wp-content\/uploads\/2025\/12\/locandina-definitiva-30-giugno.png\"><span class=\"fusion-button-icon-divider button-icon-divider-left\"><i class=\"fa-file-image fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-left\">Flyer<\/span><\/a><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-2 fusion-button-span-yes \" style=\"--awb-margin-bottom:5px;--awb-padding-top:10px;--awb-padding-right:20px;--awb-padding-bottom:10px;--awb-padding-left:20px;--button_accent_color:var(--awb-color8);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_gradient_top_color:var(--awb-color4);--button_gradient_bottom_color:var(--awb-color4);--button_gradient_top_color_hover:hsla(var(--awb-color4-h),calc(var(--awb-color4-s) - 5%),calc(var(--awb-color4-l) - 10%),var(--awb-color4-a));--button_gradient_bottom_color_hover:hsla(var(--awb-color4-h),calc(var(--awb-color4-s) - 5%),calc(var(--awb-color4-l) - 10%),var(--awb-color4-a));--button_text_transform:capitalize;--button_font_size:12px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/parcoarcheologico.cortonamaec.org\/wp-content\/uploads\/2025\/12\/CS_Mostra-Cantare-il-medioevo.pdf\"><span class=\"fusion-button-icon-divider button-icon-divider-left\"><i class=\"fa-file-pdf fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-left\">Press release<\/span><\/a><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-3 fusion-button-span-yes \" style=\"--awb-margin-bottom:5px;--awb-padding-top:10px;--awb-padding-right:20px;--awb-padding-bottom:10px;--awb-padding-left:20px;--button_accent_color:var(--awb-color8);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_gradient_top_color:var(--awb-color4);--button_gradient_bottom_color:var(--awb-color4);--button_gradient_top_color_hover:hsla(var(--awb-color4-h),calc(var(--awb-color4-s) - 5%),calc(var(--awb-color4-l) - 10%),var(--awb-color4-a));--button_gradient_bottom_color_hover:hsla(var(--awb-color4-h),calc(var(--awb-color4-s) - 5%),calc(var(--awb-color4-l) - 10%),var(--awb-color4-a));--button_text_transform:capitalize;--button_font_size:12px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/parcoarcheologico.cortonamaec.org\/wp-content\/uploads\/2025\/12\/flyer-ENG-30-giugno-1.pdf\"><span class=\"fusion-button-icon-divider button-icon-divider-left\"><i class=\"fa-file-pdf fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-left\">Exhibition Mini Guide<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>28 June 2025 &#8211; 05 October 2025<\/p>\n","protected":false},"author":2,"featured_media":5546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-5549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temporary-exhibitions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Singing the Middle Ages - MAEC Cortona | Museo dell&#039;Accademia Etrusca e della Citt\u00e0 di Cortona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Singing the Middle Ages\" \/>\n<meta property=\"og:description\" content=\"28 June 2025 - 05 October 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/\" \/>\n<meta property=\"og:site_name\" content=\"MAEC Cortona | Museo dell&#039;Accademia Etrusca e della Citt\u00e0 di Cortona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MAEC.Cortona\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T11:17:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T11:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/MAECCortona_Cantare-il-Medioevo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Menci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Menci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/\"},\"author\":{\"name\":\"Irene Menci\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#\\\/schema\\\/person\\\/45ddb946d69b87ba1773700f0de1ad6a\"},\"headline\":\"Singing the Middle Ages\",\"datePublished\":\"2025-12-09T11:17:17+00:00\",\"dateModified\":\"2026-03-10T11:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/\"},\"wordCount\":3794,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cortonamaec.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MAECCortona_Cantare-il-Medioevo.jpg\",\"articleSection\":[\"Temporary exhibitions\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/\",\"url\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/\",\"name\":\"Singing the Middle Ages - MAEC Cortona | Museo dell&#039;Accademia Etrusca e della Citt\u00e0 di Cortona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cortonamaec.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MAECCortona_Cantare-il-Medioevo.jpg\",\"datePublished\":\"2025-12-09T11:17:17+00:00\",\"dateModified\":\"2026-03-10T11:30:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cortonamaec.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MAECCortona_Cantare-il-Medioevo.jpg\",\"contentUrl\":\"https:\\\/\\\/cortonamaec.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/MAECCortona_Cantare-il-Medioevo.jpg\",\"width\":1280,\"height\":720,\"caption\":\"MAEC Cortona Cantare il Medioevo, mostra temporanea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/temporary-exhibitions\\\/singing-the-middle-ages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporary exhibitions\",\"item\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/esplora\\\/temporary-exhibitions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Singing the Middle Ages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/\",\"name\":\"MAEC Cortona | Museo dell'Accademia Etrusca e della Citt\u00e0 di Cortona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#organization\",\"name\":\"MAEC Cortona | Museo dell'Accademia Etrusca e della Citt\u00e0 di Cortona\",\"url\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cortonamaec.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/MAEC_logo_nero-copia.webp\",\"contentUrl\":\"https:\\\/\\\/cortonamaec.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/MAEC_logo_nero-copia.webp\",\"width\":1629,\"height\":1170,\"caption\":\"MAEC Cortona | Museo dell'Accademia Etrusca e della Citt\u00e0 di Cortona\"},\"image\":{\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MAEC.Cortona\",\"https:\\\/\\\/www.instagram.com\\\/maec_cortona\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@MAEC2005\"],\"description\":\"Il MAEC - Museo dell\u2019Accademia Etrusca e della Citt\u00e0 di Cortona, nel centro storico di Cortona, \u00e8 uno dei principali musei etruschi d\u2019Italia. Espone reperti di grande valore, tra cui il celebre Lampadario etrusco e la Tabula Cortonensis e comprende anche una significativa collezione egizia. Il percorso espositivo racconta la storia del territorio dall\u2019epoca etrusca al Medioevo fino all\u2019et\u00e0 moderna e contemporanea, con opere di Gino Severini, attraverso collezioni permanenti e mostre temporanee.\",\"email\":\"info@cortonamaec.org\",\"telephone\":\"0575630415\",\"legalName\":\"Accademia Etrusca ETS\",\"foundingDate\":\"1727-11-27\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/#\\\/schema\\\/person\\\/45ddb946d69b87ba1773700f0de1ad6a\",\"name\":\"Irene Menci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42d42342422de899b55f02a1b8fa293e98edaf631359c90e4a901ff8a4dccef9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42d42342422de899b55f02a1b8fa293e98edaf631359c90e4a901ff8a4dccef9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42d42342422de899b55f02a1b8fa293e98edaf631359c90e4a901ff8a4dccef9?s=96&d=mm&r=g\",\"caption\":\"Irene Menci\"},\"url\":\"https:\\\/\\\/cortonamaec.org\\\/en\\\/author\\\/irene-menci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Singing the Middle Ages - MAEC Cortona | Museo dell&#039;Accademia Etrusca e della Citt\u00e0 di Cortona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/","og_locale":"en_US","og_type":"article","og_title":"Singing the Middle Ages","og_description":"28 June 2025 - 05 October 2025","og_url":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/","og_site_name":"MAEC Cortona | Museo dell&#039;Accademia Etrusca e della Citt\u00e0 di Cortona","article_publisher":"https:\/\/www.facebook.com\/MAEC.Cortona","article_published_time":"2025-12-09T11:17:17+00:00","article_modified_time":"2026-03-10T11:30:06+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/MAECCortona_Cantare-il-Medioevo.jpg","type":"image\/jpeg"}],"author":"Irene Menci","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Menci","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#article","isPartOf":{"@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/"},"author":{"name":"Irene Menci","@id":"https:\/\/cortonamaec.org\/en\/#\/schema\/person\/45ddb946d69b87ba1773700f0de1ad6a"},"headline":"Singing the Middle Ages","datePublished":"2025-12-09T11:17:17+00:00","dateModified":"2026-03-10T11:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/"},"wordCount":3794,"commentCount":0,"publisher":{"@id":"https:\/\/cortonamaec.org\/en\/#organization"},"image":{"@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#primaryimage"},"thumbnailUrl":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/MAECCortona_Cantare-il-Medioevo.jpg","articleSection":["Temporary exhibitions"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/","url":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/","name":"Singing the Middle Ages - MAEC Cortona | Museo dell&#039;Accademia Etrusca e della Citt\u00e0 di Cortona","isPartOf":{"@id":"https:\/\/cortonamaec.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#primaryimage"},"image":{"@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#primaryimage"},"thumbnailUrl":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/MAECCortona_Cantare-il-Medioevo.jpg","datePublished":"2025-12-09T11:17:17+00:00","dateModified":"2026-03-10T11:30:06+00:00","breadcrumb":{"@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#primaryimage","url":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/MAECCortona_Cantare-il-Medioevo.jpg","contentUrl":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/12\/MAECCortona_Cantare-il-Medioevo.jpg","width":1280,"height":720,"caption":"MAEC Cortona Cantare il Medioevo, mostra temporanea"},{"@type":"BreadcrumbList","@id":"https:\/\/cortonamaec.org\/en\/temporary-exhibitions\/singing-the-middle-ages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cortonamaec.org\/en\/"},{"@type":"ListItem","position":2,"name":"Temporary exhibitions","item":"https:\/\/cortonamaec.org\/en\/esplora\/temporary-exhibitions\/"},{"@type":"ListItem","position":3,"name":"Singing the Middle Ages"}]},{"@type":"WebSite","@id":"https:\/\/cortonamaec.org\/en\/#website","url":"https:\/\/cortonamaec.org\/en\/","name":"MAEC Cortona | Museo dell'Accademia Etrusca e della Citt\u00e0 di Cortona","description":"","publisher":{"@id":"https:\/\/cortonamaec.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cortonamaec.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cortonamaec.org\/en\/#organization","name":"MAEC Cortona | Museo dell'Accademia Etrusca e della Citt\u00e0 di Cortona","url":"https:\/\/cortonamaec.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cortonamaec.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/05\/MAEC_logo_nero-copia.webp","contentUrl":"https:\/\/cortonamaec.org\/wp-content\/uploads\/2025\/05\/MAEC_logo_nero-copia.webp","width":1629,"height":1170,"caption":"MAEC Cortona | Museo dell'Accademia Etrusca e della Citt\u00e0 di Cortona"},"image":{"@id":"https:\/\/cortonamaec.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MAEC.Cortona","https:\/\/www.instagram.com\/maec_cortona\/","https:\/\/www.youtube.com\/@MAEC2005"],"description":"Il MAEC - Museo dell\u2019Accademia Etrusca e della Citt\u00e0 di Cortona, nel centro storico di Cortona, \u00e8 uno dei principali musei etruschi d\u2019Italia. Espone reperti di grande valore, tra cui il celebre Lampadario etrusco e la Tabula Cortonensis e comprende anche una significativa collezione egizia. Il percorso espositivo racconta la storia del territorio dall\u2019epoca etrusca al Medioevo fino all\u2019et\u00e0 moderna e contemporanea, con opere di Gino Severini, attraverso collezioni permanenti e mostre temporanee.","email":"info@cortonamaec.org","telephone":"0575630415","legalName":"Accademia Etrusca ETS","foundingDate":"1727-11-27","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/cortonamaec.org\/en\/#\/schema\/person\/45ddb946d69b87ba1773700f0de1ad6a","name":"Irene Menci","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/42d42342422de899b55f02a1b8fa293e98edaf631359c90e4a901ff8a4dccef9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42d42342422de899b55f02a1b8fa293e98edaf631359c90e4a901ff8a4dccef9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42d42342422de899b55f02a1b8fa293e98edaf631359c90e4a901ff8a4dccef9?s=96&d=mm&r=g","caption":"Irene Menci"},"url":"https:\/\/cortonamaec.org\/en\/author\/irene-menci\/"}]}},"_links":{"self":[{"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/posts\/5549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/comments?post=5549"}],"version-history":[{"count":4,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/posts\/5549\/revisions"}],"predecessor-version":[{"id":5555,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/posts\/5549\/revisions\/5555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/media\/5546"}],"wp:attachment":[{"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/media?parent=5549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/categories?post=5549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cortonamaec.org\/en\/wp-json\/wp\/v2\/tags?post=5549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}